{"id":1205,"date":"2021-05-26T13:34:20","date_gmt":"2021-05-26T11:34:20","guid":{"rendered":"https:\/\/www.borsikastely.eu\/elmenyek\/"},"modified":"2026-04-23T19:03:38","modified_gmt":"2026-04-23T17:03:38","slug":"zazitky","status":"publish","type":"page","link":"https:\/\/www.borsikastely.eu\/sk\/zazitky\/","title":{"rendered":"Z\u00c1\u017dITKY"},"content":{"rendered":"<p>[vc_row css=&#8220;.vc_custom_1622028858317{margin-top: 70px !important;}&#8220;][vc_column][vc_column_text]<\/p>\n<h1 style=\"text-align: center;\">HISTORICK\u00c9 Z\u00c1\u017dITKY<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1622697089556{border-bottom-width: 50px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<h2 class=\"eltoltcim\" style=\"text-align: right;\"><strong><em>CESTUJ V \u010cASE<\/em><\/strong><\/h2>\n<p>[\/vc_column_text][vc_single_image image=&#8220;2480&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#vrjatekok&#8220; el_id=&#8220;shadow1&#8243;][vc_single_image image=&#8220;2477&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#korpanorama&#8220; el_id=&#8220;shadow1&#8243;][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_single_image image=&#8220;2471&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#szabaduloszoba&#8220; el_id=&#8220;shadow1&#8243;][vc_single_image image=&#8220;2474&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#kiallitas&#8220; el_id=&#8220;shadow1&#8243;][vc_column_text]<\/p>\n<h2 class=\"eltoltcim\" style=\"text-align: left;\"><strong><em>V KA\u0160TIELI!<\/em><\/strong><\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=&#8220;vrjatekok&#8220;][vc_column][vc_separator color=&#8220;custom&#8220; accent_color=&#8220;rgba(0,0,0,0.01)&#8220;][\/vc_column][\/vc_row][vc_row el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1634394070474{padding-top: 1px !important;padding-bottom: 1px !important;border-radius: 4px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: left;\">Virtu\u00e1lna realita<\/h2>\n<p><strong>Pozor zmena! Virtu\u00e1lna reality hra v zimnej sez\u00f3ne funguje len po vopred dohodnutej rezerv\u00e1ci\u00ed!<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Odpor\u00fa\u010dan\u00e9 nad 12 rokov!<\/strong><\/p>\n<p style=\"text-align: justify;\">N\u00e1v\u0161tevn\u00edci m\u00f4\u017eu za\u017ei\u0165 ka\u0161tie\u013e a jeho okolie v dobe narodenia knie\u017ea\u0165a. Hr\u00e1\u010di sa premenia na pomocn\u00edkov pri p\u00f4rode.<\/p>\n<p style=\"text-align: justify;\">Druh\u00e9 dejstvo sa odohr\u00e1va nieko\u013eko mesiacov po naroden\u00ed Franti\u0161ka (Ferenc) II. R\u00e1k\u00f3cziho. Hr\u00e1\u010dov zavedie k s\u0165ahovaniu sa Heleny Zr\u00ednskej a mal\u00e9ho R\u00e1k\u00f3cziho.<\/p>\n<p style=\"text-align: justify;\">V tre\u0165om dejstve sa hr\u00e1\u010di stan\u00fa \u00fa\u010dastn\u00edkmi obk\u013e\u00fa\u010denia hradu a bojov o neho.<\/p>\n<p style=\"text-align: justify;\">\u0160tvrt\u00e9 dejstvo sa op\u00e4\u0165 odohr\u00e1va nesk\u00f4r. R\u00e1k\u00f3czi sa vracia do ka\u0161tie\u013ea u\u017e ako dospel, kde ho v\u00edtaj\u00fa sviato\u010dn\u00fdm v\u00fdstrelom a ve\u013ek\u00fdm pohosten\u00edm. Hr\u00e1\u010di sa z\u00fa\u010dast\u0148uj\u00fa hry ako pomocn\u00edci pri priv\u00edtan\u00ed knie\u017ea\u0165a.<\/p>\n<p>[\/vc_column_text][vc_column_text]<div class=\"eg-filmstrip-wrap eg-wrap\" data-lightbox-type=\"pretty_photo\"\n         data-pretty_photo-theme =\"pp_default\"\n         data-pretty_photo-social =\"false\"\n          data-gallery-id=\"yNy76HGopf\"\n     data-lightbox-status=\"true\"\n          >\n         \n    <div class=\"eg-filmstrip-outer-wrap eg-filmstrip-outer-layout-5\">\n        <div class=\"eg-filmstrip-items-outerwrap\">\n            <div class=\"eg-filmstrip-items-wrap eg-filmstrip-layout-5\"\n                 data-pause-duration=\"2500\"\n                 data-transition-duration=\"500\"\n                 data-mode=\"horizontal\"\n                 data-next-previous-controls=\"false\"\n                 data-play-pause-controls=\"false\"\n                 data-auto-start=\"false\"\n                 data-adaptive-height=\"true\"\n                 data-pager=\"false\"\n                 data-pager-type=\"full\"\n                 data-filmstrip-id=\"HuHPWCrjfP\"\n\n                 >\n                     <div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_2D1ioa84OOk6YHt\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr001.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_3]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"1\"\n                   data-total-items=\"3\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr001.jpg\" alt=\"Virtr001\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Virtr001<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Virtr001<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Virtr001<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Virtr001<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_XFdTfJvuJkAluZQ\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr002.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_3]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"2\"\n                   data-total-items=\"3\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr002.jpg\" alt=\"Virtr002\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Virtr002<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Virtr002<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Virtr002<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Virtr002<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_kTrsLWgvekbewKg\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr003.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_3]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"3\"\n                   data-total-items=\"3\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr003.jpg\" alt=\"Virtr003\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Virtr003<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Virtr003<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Virtr003<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Virtr003<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div>            <\/div>\n        <\/div>\n        <div class=\"eg-filmstrip-pager-outerwrap\">\n            <div class=\"eg-filmstrip-pager\" id=\"eg-pager-HuHPWCrjfP\" data-min-slides=\"3\" data-max-slides=\"3\" data-slide-width=\"170\" data-move-slides=\"1\">\n                                        <a href=\"\" data-slide-index=\"0\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr001-700x667.jpg\" alt=\"Virtr001\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Virtr001<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"1\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr002-700x666.jpg\" alt=\"Virtr002\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Virtr002<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"2\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/virtr003-700x666.jpg\" alt=\"Virtr003\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Virtr003<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                    <\/div>\n            <div class=\"eg-flimstrip-caption-tooltip\"><\/div>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n            <style>\r\n            <\/style>\r\n            [\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_column_text el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1767706102930{margin-right: 1px !important;margin-left: 1px !important;border-radius: 4px !important;}&#8220;]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: left;\">CENN\u00cdK<\/h2>\n<table style=\"border: none;\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\">DOSPEL\u00dd<\/td>\n<td style=\"text-align: right;\">10 EUR\/OSOBA<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">\u0160TUDENT\/D \u00d4CHODCA\/ *Z\u0164P<\/td>\n<td style=\"text-align: right;\">5 EUR\/OSOBA<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>*Vstup pre sprev\u00e1dzaj\u00facu osobu je bezplatn\u00fd.<\/em><br \/>\n<em>V na\u0161ich pokladniach je mo\u017enos\u0165 platby iba v mene euro.<\/em><br \/>\n<em>Uveden\u00e9 ceny s\u00fa informat\u00edvne, vyhradzujeme si pr\u00e1vo zmeny uveden\u00fdch cien.<\/em>[\/vc_column_text][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_id=&#8220;szabaduloszoba&#8220;][vc_column][vc_separator color=&#8220;custom&#8220; accent_color=&#8220;rgba(0,0,0,0.01)&#8220;][\/vc_column][\/vc_row][vc_row el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1634394130655{padding-top: 1px !important;padding-bottom: 1px !important;border-radius: 4px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<h2 class=\"kiemeltcim\">Escape room<\/h2>\n<p><strong>Pozor zmena! \u00danikov\u00e1 izba v zimnej sez\u00f3ne funguje len po vopred dohodnutej rezerv\u00e1ci\u00ed!<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Do 12 rokov len s dospel\u00fdm doprovodom!<\/strong><\/p>\n<p>\u201e(..) od siln\u00e9ho buchnutia sa otvoria dvere bl\u00edzko postele, a mnou dvaja dobre zn\u00e1my stotn\u00edci z vojensk\u00e9ho mil\u00e9nia Salm v ruk\u00e1ch so svie\u010dkou a ozbrojen\u00ed pi\u0161to\u013eami zatarasia poste\u013e a m\u0148a v mene cis\u00e1ra vyhl\u00e1sia za v\u00e4z\u0148a.\u201d<\/p>\n<p>R\u00e1k\u00f3czi sa dostal do Viedensk\u00e9ho Nov\u00e9ho Mesta spolu s \u010fal\u0161\u00edmi povstalcami proti cis\u00e1rovi. Bolo to pre\u0148ho jasn\u00e9: ak neujde, trest smrti ho nem\u00f4\u017ee min\u00fa\u0165, ke\u010f\u017ee bol uv\u00e4znen\u00fd za velezradu. Svoj \u00fatek riadne napl\u00e1noval.<\/p>\n<p>\u00da\u010dastn\u00edci hry v \u00fanikovej izbe musia napl\u00e1nova\u0165 \u00fatek knie\u017ea\u0165a.[\/vc_column_text][vc_column_text]<div class=\"eg-filmstrip-wrap eg-wrap\" data-lightbox-type=\"pretty_photo\"\n         data-pretty_photo-theme =\"pp_default\"\n         data-pretty_photo-social =\"false\"\n          data-gallery-id=\"7fNV0XeurK\"\n     data-lightbox-status=\"true\"\n          >\n         \n    <div class=\"eg-filmstrip-outer-wrap eg-filmstrip-outer-layout-5\">\n        <div class=\"eg-filmstrip-items-outerwrap\">\n            <div class=\"eg-filmstrip-items-wrap eg-filmstrip-layout-5\"\n                 data-pause-duration=\"2500\"\n                 data-transition-duration=\"500\"\n                 data-mode=\"horizontal\"\n                 data-next-previous-controls=\"false\"\n                 data-play-pause-controls=\"false\"\n                 data-auto-start=\"false\"\n                 data-adaptive-height=\"true\"\n                 data-pager=\"false\"\n                 data-pager-type=\"full\"\n                 data-filmstrip-id=\"zZx87CPM1f\"\n\n                 >\n                     <div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_scMIC07EZRqtlD9\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob001.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_4]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"1\"\n                   data-total-items=\"5\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob001.jpg\" alt=\"Szabszob001\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Szabszob001<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Szabszob001<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Szabszob001<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Szabszob001<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_fDz0l3CrmPcWJoh\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob002.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_4]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"2\"\n                   data-total-items=\"5\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob002.jpg\" alt=\"Szabszob002\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Szabszob002<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Szabszob002<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Szabszob002<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Szabszob002<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_NQuzz7JGKIxabSN\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob003.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_4]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"3\"\n                   data-total-items=\"5\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob003.jpg\" alt=\"Szabszob003\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Szabszob003<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Szabszob003<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Szabszob003<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Szabszob003<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_j8rShMVTdiIqesO\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob004.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_4]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"4\"\n                   data-total-items=\"5\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob004.jpg\" alt=\"Szabszob004\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Szabszob004<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Szabszob004<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Szabszob004<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Szabszob004<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_wfF1Pe8yURgs3sk\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob005.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_4]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"5\"\n                   data-total-items=\"5\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob005.jpg\" alt=\"Szabszob005\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Szabszob005<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Szabszob005<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Szabszob005<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Szabszob005<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div>            <\/div>\n        <\/div>\n        <div class=\"eg-filmstrip-pager-outerwrap\">\n            <div class=\"eg-filmstrip-pager\" id=\"eg-pager-zZx87CPM1f\" data-min-slides=\"3\" data-max-slides=\"3\" data-slide-width=\"170\" data-move-slides=\"1\">\n                                        <a href=\"\" data-slide-index=\"0\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob001-700x665.jpg\" alt=\"Szabszob001\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Szabszob001<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"1\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob002-700x665.jpg\" alt=\"Szabszob002\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Szabszob002<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"2\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob003-700x665.jpg\" alt=\"Szabszob003\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Szabszob003<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"3\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob004-700x665.jpg\" alt=\"Szabszob004\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Szabszob004<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"4\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/szabszob005-700x665.jpg\" alt=\"Szabszob005\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Szabszob005<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                    <\/div>\n            <div class=\"eg-flimstrip-caption-tooltip\"><\/div>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n            <style>\r\n            <\/style>\r\n            [\/vc_column_text][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_column_text el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1767706112354{border-radius: 4px !important;}&#8220;]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: left;\">CENN\u00cdK<\/h2>\n<table style=\"border: none;\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\">DOSPEL\u00dd<\/td>\n<td style=\"text-align: right;\">15 EUR\/OSOBA<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">\u0160TUDENT\/ D\u00d4CHODCA\/ *Z\u0164P<\/td>\n<td style=\"text-align: right;\">10 EUR\/OSOBA<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">SKUPINOV\u00dd &#8211; viac ako 2 OSOBY<\/td>\n<td style=\"text-align: right;\">13 EUR\/OSOBA<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>*Vstup pre sprev\u00e1dzaj\u00facu osobu je bezplatn\u00fd.<\/em><br \/>\n<em>V na\u0161ich pokladniach je mo\u017enos\u0165 platby iba v mene euro.<\/em><br \/>\n<em>Uveden\u00e9 ceny s\u00fa informat\u00edvne, vyhradzujeme si pr\u00e1vo zmeny uveden\u00fdch cien.<\/em><\/p>\n<p><em>Ak m\u00e1te z\u00e1ujem vysk\u00fa\u0161a\u0165 si na\u0161u \u00fanikov\u00fa izbu, odpor\u00fa\u010dame V\u00e1m vopred si rezervova\u0165 \u010das aj d\u00e1tum na uvedenom tel. \u010d\u00edsle <a href=\"tel:+421948140880\">+421948140880<\/a>, alebo na e-mailovej adrese: <a href=\"mailto:office@rakoczino.eu\">office@rakoczino.eu<\/a>\u00a0preto\u017ee miestnos\u0165 m\u00f4\u017ee by\u0165 u\u017e rezervovan\u00e1 v po\u017eadovanom \u010dase. \u010eakujeme!<\/em>[\/vc_column_text][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_id=&#8220;korpanorama&#8220;][vc_column][vc_separator color=&#8220;custom&#8220; accent_color=&#8220;rgba(0,0,0,0.01)&#8220;][\/vc_column][\/vc_row][vc_row el_class=&#8220;arakdoboz&#8220; el_id=&#8220;korpanorama&#8220; css=&#8220;.vc_custom_1634394146997{padding-top: 1px !important;padding-bottom: 1px !important;border-radius: 4px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: left;\">Panoramatick\u00e9 premietanie<\/h2>\n<p style=\"text-align: justify;\">V premietacej s\u00e1le s kapacitou 15 os\u00f4b oh\u00faria div\u00e1kov filmy premietan\u00e9 na pl\u00e1tne s 360 stup\u0148ovou panor\u00e1mou. Filmy s d\u013a\u017ekou 5-6 min\u00fat s\u00fa ve\u013ekolep\u00e9 a z\u00e1rove\u0148 informat\u00edvne, dopraj\u00fa nezabudnute\u013en\u00e9 chv\u00edle pre v\u0161etky vekov\u00e9 kateg\u00f3rie. Vtipn\u00fd animovan\u00fd film predstav\u00ed \u017eivot Franti\u0161ka (Ferenc) II. R\u00e1k\u00f3cziho, sediac v neoby\u010dajnom lietaj\u00facom tanieri m\u00f4\u017eeme spozn\u00e1va\u0165 domorod\u00e9 druhy drev\u00edn Karpatskej kotliny, m\u00f4\u017eeme lieta\u0165 ponad zn\u00e1me pam\u00e4tn\u00e9 miesta R\u00e1k\u00f3cziho. Ozajstnou v\u00fdnimo\u010dnos\u0165ou je film predstavuj\u00faci ma\u010farsk\u00e9 a slovensk\u00e9 tance kari\u010dky, v ktorom sediac v strede kruhu m\u00f4\u017eeme obdivova\u0165 tane\u010dn\u00edkov kari\u010dky.<\/p>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text]<div class=\"eg-filmstrip-wrap eg-wrap\" data-lightbox-type=\"pretty_photo\"\n         data-pretty_photo-theme =\"pp_default\"\n         data-pretty_photo-social =\"false\"\n          data-gallery-id=\"3IJJyFmZZB\"\n     data-lightbox-status=\"true\"\n          >\n         \n    <div class=\"eg-filmstrip-outer-wrap eg-filmstrip-outer-layout-5\">\n        <div class=\"eg-filmstrip-items-outerwrap\">\n            <div class=\"eg-filmstrip-items-wrap eg-filmstrip-layout-5\"\n                 data-pause-duration=\"2500\"\n                 data-transition-duration=\"500\"\n                 data-mode=\"horizontal\"\n                 data-next-previous-controls=\"false\"\n                 data-play-pause-controls=\"false\"\n                 data-auto-start=\"false\"\n                 data-adaptive-height=\"true\"\n                 data-pager=\"false\"\n                 data-pager-type=\"full\"\n                 data-filmstrip-id=\"P7RC21zgv1\"\n\n                 >\n                     <div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_HDQ6Zsd4Bf5d16N\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan01.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_5]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"1\"\n                   data-total-items=\"6\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan01.jpg\" alt=\"Korpan01\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Korpan01<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Korpan01<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Korpan01<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Korpan01<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_vvbSfb3uxkUd0ZN\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan02.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_5]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"2\"\n                   data-total-items=\"6\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan02.jpg\" alt=\"Korpan02\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Korpan02<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Korpan02<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Korpan02<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Korpan02<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_nGreLqGYuiezvfE\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan03.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_5]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"3\"\n                   data-total-items=\"6\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan03.jpg\" alt=\"Korpan03\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Korpan03<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Korpan03<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Korpan03<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Korpan03<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_iLauDqFFUd1Oq0N\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan04.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_5]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"4\"\n                   data-total-items=\"6\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan04.jpg\" alt=\"Korpan04\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Korpan04<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Korpan04<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Korpan04<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Korpan04<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_extFMf7seBLsagI\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan05.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_5]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"5\"\n                   data-total-items=\"6\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan05.jpg\" alt=\"Korpan05\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Korpan05<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Korpan05<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Korpan05<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Korpan05<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_Pzt148qJNlWNanX\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan06.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_5]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"6\"\n                   data-total-items=\"6\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan06.jpg\" alt=\"Korpan06\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Korpan06<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Korpan06<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Korpan06<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Korpan06<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div>            <\/div>\n        <\/div>\n        <div class=\"eg-filmstrip-pager-outerwrap\">\n            <div class=\"eg-filmstrip-pager\" id=\"eg-pager-P7RC21zgv1\" data-min-slides=\"3\" data-max-slides=\"3\" data-slide-width=\"170\" data-move-slides=\"1\">\n                                        <a href=\"\" data-slide-index=\"0\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan01-700x159.jpg\" alt=\"Korpan01\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Korpan01<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"1\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan02-700x159.jpg\" alt=\"Korpan02\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Korpan02<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"2\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan03-700x159.jpg\" alt=\"Korpan03\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Korpan03<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"3\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan04-700x159.jpg\" alt=\"Korpan04\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Korpan04<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"4\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan05-700x159.jpg\" alt=\"Korpan05\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Korpan05<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"5\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/korpan06-700x159.jpg\" alt=\"Korpan06\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Korpan06<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                    <\/div>\n            <div class=\"eg-flimstrip-caption-tooltip\"><\/div>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n            <style>\r\n            <\/style>\r\n            [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_row_inner][vc_column_inner][vc_column_text el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1756445912753{border-radius: 4px !important;}&#8220;]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: left;\">CENN\u00cdK<\/h2>\n<table style=\"border: none;\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\">DOSPEL\u00dd<\/td>\n<td style=\"text-align: right;\">2,5 EUR\/OSOBA\/FILM<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">\u0160TUDENT\/D\u00d4CHODCA\/<br \/>\n*ZDRAVOTNE POSTIHNUT\u00dd<\/td>\n<td style=\"text-align: right;\">1,5 EUR\/OSOBA\/FILM<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">2 ZAK\u00daPEN\u00c9 FILMY<\/td>\n<td style=\"text-align: right;\">4 EUR\/DOSPEL\u00c1 OSOBA<br \/>\n2,5 EUR\/\u0160TUDENT\/D\u00d4CHODCA\/ *OSOBY<br \/>\nSO ZDRAVOTN\u00ddM POSTIHNUT\u00cdM<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">3 ZAK\u00daPEN\u00c9 FILMY<\/td>\n<td style=\"text-align: right;\">6 EUR\/DOSPEL\u00c1 OSOBA<br \/>\n4 EUR\/\u0160TUDENT\/D\u00d4CHODCA\/ *OSOBY<br \/>\nSO ZDRAVOTN\u00ddM POSTIHNUT\u00cdM<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">4 ZAK\u00daPEN\u00c9 FILMY<\/td>\n<td style=\"text-align: right;\">9 EUR\/DOSPEL\u00c1 OSOBA<br \/>\n5 EUR\/\u0160TUDENT\/D\u00d4CHODCA\/ *OSOBY<br \/>\nSO ZDRAVOTN\u00ddM POSTIHNUT\u00cdM<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">5 ZAK\u00daPEN\u00c9 FILMY<\/td>\n<td style=\"text-align: right;\">11 EUR\/DOSPEL\u00c1 OSOBA<br \/>\n6 EUR\/\u0160TUDENT\/D\u00d4CHODCA\/ *OSOBY<br \/>\nSO ZDRAVOTN\u00ddM POSTIHNUT\u00cdM<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Deti do 6 rokov maj\u00fa vstup zdarma.<\/p>\n<p><em>*Vstup pre sprev\u00e1dzaj\u00facu osobu je bezplatn\u00fd.<\/em><br \/>\n<em>V na\u0161ich pokladniach je mo\u017enos\u0165 platby iba v mene euro.<\/em><br \/>\n<em>Uveden\u00e9 ceny s\u00fa informat\u00edvne, vyhradzujeme si pr\u00e1vo zmeny uveden\u00fdch cien.<\/em>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_id=&#8220;kiallitas&#8220;][vc_column][vc_separator color=&#8220;custom&#8220; accent_color=&#8220;rgba(0,0,0,0.01)&#8220;][\/vc_column][\/vc_row][vc_row el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1634394161283{padding-top: 1px !important;padding-bottom: 1px !important;border-radius: 4px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: right;\">Tri narodenia R\u00e1k\u00f3cziho<\/h2>\n<p style=\"text-align: justify;\">V expoz\u00edci\u00ed s n\u00e1zvom Tri narodenia R\u00e1k\u00f3cziho sa okrem hist\u00f3rie ka\u0161tie\u013ea m\u00f4\u017eete obozn\u00e1mi\u0165 s fungovan\u00edm panstva, s novovekou Eur\u00f3pou a samozrejme s rodinou R\u00e1k\u00f3czi. \u017divot Franti\u0161ka (Ferenc) II. R\u00e1k\u00f3cziho m\u00f4\u017eete sledova\u0165 nielen od narodenia, ale a\u017e od o\u010dak\u00e1vania die\u0165a\u0165a po smr\u0165 knie\u017ea\u0165a v Tekirda\u011f, a v neposlednom rade V\u00e1s prenesieme k pamiatkam, ktor\u00e9 s\u00fa dodnes \u00fazko spojen\u00e9 s uctievan\u00edm hrdinu. Mysliac na deti i dospel\u00fdch, si m\u00f4\u017eete vybra\u0165 zo \u0161irokej \u0161k\u00e1ly t\u00e9m pod\u013ea svojich predst\u00e1v a samozrejme sme nezabudli ani na interakt\u00edvne hry.<\/p>\n<p style=\"text-align: justify;\">Kreat\u00edvny t\u00edm Univerzity umenia a dizajnu Moholy-Nagy z Budape\u0161ti, za \u00fa\u010dasti odborn\u00edkov vysn\u00edval t\u00fato zauj\u00edmav\u00fa interakt\u00edvnu expoz\u00edciu, ktor\u00fa si m\u00f4\u017eete pozrie\u0165 len v na\u0161ej in\u0161tit\u00facii a to na ploche 1 000 m<sup>2<\/sup>.<\/p>\n<p>[\/vc_column_text][vc_column_text]<div class=\"eg-filmstrip-wrap eg-wrap\" data-lightbox-type=\"pretty_photo\"\n         data-pretty_photo-theme =\"pp_default\"\n         data-pretty_photo-social =\"false\"\n          data-gallery-id=\"151xc7a2Sb\"\n     data-lightbox-status=\"true\"\n          >\n         \n    <div class=\"eg-filmstrip-outer-wrap eg-filmstrip-outer-layout-5\">\n        <div class=\"eg-filmstrip-items-outerwrap\">\n            <div class=\"eg-filmstrip-items-wrap eg-filmstrip-layout-5\"\n                 data-pause-duration=\"2500\"\n                 data-transition-duration=\"500\"\n                 data-mode=\"horizontal\"\n                 data-next-previous-controls=\"false\"\n                 data-play-pause-controls=\"false\"\n                 data-auto-start=\"false\"\n                 data-adaptive-height=\"true\"\n                 data-pager=\"false\"\n                 data-pager-type=\"full\"\n                 data-filmstrip-id=\"gUU1EsF1sF\"\n\n                 >\n                     <div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_aXWhbMw2XQMzGFS\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall007.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"1\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall007.jpg\" alt=\"Kiall007\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Kiall007<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Kiall007<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Kiall007<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Kiall007<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_gVUTTBqvWTiVgwv\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall008.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"2\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall008.jpg\" alt=\"Kiall008\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Kiall008<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Kiall008<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Kiall008<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Kiall008<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_wh4raW3BsZuKVKg\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall010.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"3\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall010.jpg\" alt=\"Kiall010\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Kiall010<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Kiall010<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Kiall010<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Kiall010<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_q9XTtVxApdFKGiM\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall011.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"4\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall011.jpg\" alt=\"Kiall011\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\">Kiall011<\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\">Kiall011<\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\">Kiall011<\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\">Kiall011<\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_jp76Tsa5fRrTMLa\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall001.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"5\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall001.jpg\" alt=\"\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\"><\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\"><\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\"><\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_XsiqxFHaYfabiQr\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall002.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"6\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall002.jpg\" alt=\"\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\"><\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\"><\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\"><\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_PcfNyNUvCDAxVE0\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall003.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"7\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall003.jpg\" alt=\"\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\"><\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\"><\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\"><\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_prssy7pTVqa8xkZ\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall004.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"8\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall004.jpg\" alt=\"\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\"><\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\"><\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\"><\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_xgeYHH1UizAPTsW\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall005.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"9\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall005.jpg\" alt=\"\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\"><\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\"><\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\"><\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div><div class=\"eg-each-item eg-no-hover \" data-eg-item-key=\"eg_item_rXQ3ugj4DhCTNnA\">\n    \n\n            <div class=\"eg-masonary-padding\">\n            <div class=\"eg-overlay-wrapper\" onclick=\"\">\n\n                <a href=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall006.jpg\"\n                   data-lightbox-type=\"pretty_photo\"\n                   rel=\"prettyPhoto[gallery_2]\"\n                   title=\"\"\n                   data-item-type=\"image\"\n                   data-index=\"10\"\n                   data-total-items=\"10\"\n                   >\n                    <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall006.jpg\" alt=\"\"\/>\n                <\/a>\n                <div class=\"eg-mask\">\n                    <div class=\"eg-inner-wrapper\">\n                        <div class=\"eg-content-holder\">\r\n            <span class=\"eg-title eg-main-title\"><\/span>\r\n                <div class=\"eg-caption\">\r\n                            <span class=\"eg-title\" style=\"display:none\"><\/span>\r\n                        \r\n                <p><\/p>\r\n                    <\/div>\r\n        <\/div>                    <\/div>\n                    <span class=\"add\" style=\"display: none\">\n                        <i class=\"fa fa-plus\"><\/i>\n                    <\/span>\n                                            <div class=\"eg-caption-holder\" style=\"display: none\">\n                                                            <span class=\"eg-title\"><\/span>\n                                                                                        <p><\/p>\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"slider-overlay\"><\/div>\n                            <\/div>\n                            <div class=\"eg-slider-caption eg-filmstrip-caption\">\n                                            <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                                <p><\/p>\n                                    <\/div>\n                    <\/div>\n        <!---Blog Layout -->\n<\/div>            <\/div>\n        <\/div>\n        <div class=\"eg-filmstrip-pager-outerwrap\">\n            <div class=\"eg-filmstrip-pager\" id=\"eg-pager-gUU1EsF1sF\" data-min-slides=\"3\" data-max-slides=\"3\" data-slide-width=\"170\" data-move-slides=\"1\">\n                                        <a href=\"\" data-slide-index=\"0\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall007-700x562.jpg\" alt=\"Kiall007\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Kiall007<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"1\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall008-700x563.jpg\" alt=\"Kiall008\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Kiall008<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"2\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall010-700x463.jpg\" alt=\"Kiall010\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Kiall010<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"3\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/06\/kiall011-700x666.jpg\" alt=\"Kiall011\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\">Kiall011<\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"4\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall001-700x665.jpg\" alt=\"\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"5\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall002-700x665.jpg\" alt=\"\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"6\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall003-700x665.jpg\" alt=\"\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"7\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall004-700x665.jpg\" alt=\"\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"8\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall005-700x665.jpg\" alt=\"\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                                <a href=\"\" data-slide-index=\"9\">\n                            <img src=\"https:\/\/www.borsikastely.eu\/wp-content\/uploads\/2021\/05\/kiall006-700x665.jpg\" alt=\"\"\/>\n                            <div class=\"eg-filmstrip-caption\" style=\"display:none;\">\n                                <span class=\"eg-title\" style=\"display:none\"><\/span>\n                                <p><\/p>\n                            <\/div>\n                        <\/a>\n\n                                    <\/div>\n            <div class=\"eg-flimstrip-caption-tooltip\"><\/div>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n            <style>\r\n            <\/style>\r\n            [\/vc_column_text][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_row_inner][vc_column_inner][vc_column_text el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1767706143986{border-radius: 4px !important;}&#8220;]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: left;\">CENN\u00cdK<\/h2>\n<table style=\"border: none;\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\">DOSPEL\u00dd<\/td>\n<td style=\"text-align: right;\">10 EUR\/OSOBA<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">\u0160TUDENT\/D\u00d4CHODCA\/*Z<\/td>\n<td style=\"text-align: right;\">6 EUR\/OSOBA<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">RODINN\u00dd L\u00cdSTOK<br \/>\n(2 DOSPEL\u00dd A 1 \u0160TUDENT)<br \/>\nKA\u017dD\u00dd \u010eAL\u0160\u00cd \u0160TUDENT<\/td>\n<td style=\"text-align: right;\">24 EUR<\/p>\n<p>3 EUR<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">SKUPINA \u2013 NAD 15 OS\u00d4B DOSPEL\u00cd<\/td>\n<td style=\"text-align: right;\">9 EUR\/OSOBA<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">SKUPINA \u2013 NAD 15 OS\u00d4B \u0160TUDENT\/D\u00d4CHODCA\/*Z\u0164P<\/td>\n<td style=\"text-align: right;\">5 EUR\/OSOBA<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">SPRIEVODCOVSK\u00dd POPLATOK (NUTN\u00c1 PREDBE\u017dN\u00c1<br \/>\nREGISTR\u00c1CIA \u2013 1 skupina max. 30 os\u00f4b)<\/td>\n<td style=\"text-align: right;\">15\u00a0EUR\/v\u00fdstava\/skupina<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Deti do 6 rokov maj\u00fa vstup zdarma.<\/p>\n<p>V pr\u00edpade skup\u00edn je potrebn\u00e1 rezerv\u00e1cia term\u00ednu prehliadky e-mailom: <a href=\"mailto:muzeum@rakoczino.eu\">muzeum@rakoczino.eu<\/a>.<\/p>\n<p>V pr\u00edpade \u0161tudentsk\u00fdch skup\u00edn\/exkurzi\u00ed je vstup bezplatn\u00fd pre 1 sprev\u00e1dzaj\u00facej dospelej osoby na 10<br \/>\n\u0161tudentov\/\u017eiakov.<\/p>\n<p>Vyhradzujeme si pr\u00e1vo na zmenu \u010dasu vstupov v pr\u00edpade potreby pre individu\u00e1lnej prehliadky!<\/p>\n<p><em>*Vstup pre sprev\u00e1dzaj\u00facu osobu je bezplatn\u00fd.<\/em><br \/>\n<em>V na\u0161ich pokladniach je mo\u017enos\u0165 platby iba v mene euro.<\/em><br \/>\n<em>Uveden\u00e9 ceny s\u00fa informat\u00edvne, vyhradzujeme si pr\u00e1vo zmeny uveden\u00fdch cien.<\/em><\/p>\n<p>V\u00fdstava nie je pr\u00edstupn\u00e1 pre psov a in\u00fdch dom\u00e1cich mil\u00e1\u010dikov.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_id=&#8220;taborisko&#8220;][vc_column][vc_separator color=&#8220;custom&#8220; accent_color=&#8220;rgba(0,0,0,0.01)&#8220;][\/vc_column][\/vc_row][vc_row el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1634394435467{padding-top: 1px !important;padding-bottom: 1px !important;border-radius: 4px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<h2 class=\"kiemeltcim\" style=\"text-align: left;\">T\u00e1borisko pri R\u00e1k\u00f3cziho ka\u0161tieli<\/h2>\n<p style=\"text-align: center;\"><strong>Povolen\u00e9 len od 12 rokov!<\/strong><\/p>\n<p style=\"text-align: justify;\">Oddychov\u00fd bod pre vodn\u00fdch a cykloturistov, ktor\u00e9 sme zriadili pomocou Terra Incognita \u2013 podporn\u00fd program Ko\u0161ick\u00e9ho samospr\u00e1vneho kraja, V\u00e1s o\u010dak\u00e1va oddychom v malebnej pr\u00edrode pobre\u017eia Bodrog s kr\u00e1snym obnoven\u00fdm renesan\u010dn\u00fdm ka\u0161tie\u013eom R\u00e1k\u00f3cziovcov v pozad\u00ed. M\u00e1te tu mo\u017enos\u0165 na piknik, v\u00fdpo\u017ei\u010danie kajakov a kanoe.<\/p>\n<p>[\/vc_column_text][vc_single_image image=&#8220;3248&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220;][vc_single_image image=&#8220;3267&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220;][vc_tta_accordion active_section=&#8220;0&#8243; collapsible_all=&#8220;true&#8220;][vc_tta_section title=&#8220;Otv\u00e1racia doba&#8220; tab_id=&#8220;1657283011894-d8b48033-597c5716-ce85&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Otv\u00e1racia doba \/ <strong>Nyitva tart\u00e1s <\/strong>\/ Opening Hours<\/h2>\n<p style=\"text-align: center;\">j\u00fal &#8211; august \/ <strong>j\u00falius &#8211; augusztus <\/strong>\/ July \u2013 August<\/p>\n<p style=\"text-align: center;\">ka\u017ed\u00fd de\u0148 \/ <strong>minden nap <\/strong>\/ every day<\/p>\n<p style=\"text-align: center;\">9:00 \u2013 18:00<\/p>\n<p style=\"text-align: center;\">september \u2013 j\u00fan \/ <strong>szeptember \u2013 j\u00fanius <\/strong>\/ September \u2013 June<\/p>\n<p style=\"text-align: center;\">na z\u00e1klade predbe\u017enej dohody \/ <strong>el<\/strong><strong>\u0151zetes egyeztet\u00e9s alapj\u00e1n<\/strong> \/ individual agreements<\/p>\n<p style=\"text-align: center;\">Vodn\u00fd t\u00e1bor je zatvoren\u00e1 od 1.10-30.4\/ <strong>A t\u00e1bor z\u00e1rva Okt\u00f3ber 1. &#8211; \u00c1prilis 30.<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"mailto:office@rakoczino.eu\">office@rakoczino.eu<\/a><\/p>\n<p style=\"text-align: center;\">v\u00a0pr\u00edpade potreby volajte \/<br \/>\n<strong>sz\u00fcks\u00e9g eset\u00e9n k\u00e9rem az al\u00e1bbi sz\u00e1mot h\u00edvj\u00e1k <\/strong>\/<br \/>\nin case of need, please contact us<\/p>\n<p style=\"text-align: center;\">+421-948-740-774<\/p>\n<p style=\"text-align: center;\">Pren\u00e1jom a\u00a0stanov\u00e9 miesta si m\u00f4\u017eete registrova\u0165 na:<\/p>\n<p style=\"text-align: center;\"><strong>B\u00e9rl\u00e9st \u00e9s s\u00e1torhelyet weboldalunkon regisztr\u00e1lhatnak: <\/strong><\/p>\n<p style=\"text-align: center;\">For renting and tent placement you can register on:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.borsikastely.eu\/sk\/rezervacia-kajakov-a-kanoe\/\">borsikastely.eu<\/a><\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][vc_btn title=&#8220;Rezerv\u00e1cia kajakov a kanoe&#8220; style=&#8220;custom&#8220; custom_background=&#8220;#3a544d&#8220; custom_text=&#8220;#e9bc03&#8243; link=&#8220;url:https%3A%2F%2Fwww.borsikastely.eu%2Fsk%2Frezervacia-kajakov-a-kanoe%2F&#8220;][vc_single_image image=&#8220;4614&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220;][vc_btn title=&#8220;Turistick\u00e9 trasy&#8220; style=&#8220;custom&#8220; custom_background=&#8220;#3a544d&#8220; custom_text=&#8220;#e9bc03&#8243; link=&#8220;url:https%3A%2F%2Fwww.borsikastely.eu%2Fsk%2Fturisticke-trasy%2F&#8220;][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_column_text el_class=&#8220;arakdoboz&#8220; css=&#8220;.vc_custom_1776963815446{border-radius: 4px !important;}&#8220;]<\/p>\n<h2 class=\"kiemeltcim\">Cenn\u00edk \/ <strong>\u00c1rak<\/strong> \/ Fees<\/h2>\n<p>Piknikov\u00fd pr\u00edplatok \/ <strong>Piknikd\u00edj <\/strong>\/ Picnic Fee \u00a0 1,50 Eur\/osoba\/<strong>f\u0151<\/strong>\/person<\/p>\n<ul>\n<li>slu\u017eby, ktor\u00e9 v r\u00e1mci pr\u00edplatku si m\u00f4\u017eete vyu\u017e\u00edva\u0165: opekanie na ohnisku, letn\u00e1 kuchy\u0148a, wifi, vodu, toalety<\/li>\n<li>szolg\u00e1ltat\u00e1sok, melyeket ennek keret\u00e9ben ig\u00e9nybe vehetnek: t\u0171zrak\u00f3helyek, ny\u00e1ri konyha, wifi, v\u00edzhaszn\u00e1lat, mosd\u00f3 haszn\u00e1lata<\/li>\n<li>services to use within: fire-places, summer kitchen, wifi, water supply, toilets<\/li>\n<\/ul>\n<p>Umiestnenie stanu \/ <strong>S\u00e1torhely d\u00edja <\/strong>\/ Tent Fee<\/p>\n<p>4,50 Eur\/stan pre dospel\u00fdch\/ <strong>feln<\/strong><strong>\u0151ttek r\u00e9sz\u00e9re <\/strong>\/for adults<\/p>\n<p>3,00 Eur\/stan deti, ml\u00e1de\u017e \/ <strong>gyerekek, di\u00e1kok<\/strong> \/ kids, youth<\/p>\n<p><strong>Cenn\u00edk T\u00e1bor :<\/strong><\/p>\n<ul>\n<li><strong>Dospel\u00e1 osoba\/ Noc\/ 5<\/strong><strong>\u20ac<\/strong><\/li>\n<li><strong>Die\u0165a do 15 rokov\/ Noc\/ 4<\/strong><strong>\u20ac<\/strong><\/li>\n<li><strong>Miestna da\u0148: 1,5<\/strong><strong>\u20ac<\/strong><\/li>\n<li><strong>V cene je\u00a0<\/strong><strong>zahrnut\u00e9<\/strong><strong>: <\/strong>ohnisko, letn\u00e1 kuchy\u0148a, Wifi, pitn\u00e1 voda, sprcha a\u00a0WC ,elektrina<\/li>\n<\/ul>\n<p>Pren\u00e1jom kajakov a\u00a0kanoe \/ <strong>Kajak \u00e9s kenu k<\/strong><strong>\u00f6lcs\u00f6nz\u00e9s<\/strong> \/ Rent of kayaks and canoes<\/p>\n<p>cez t\u00fd\u017ede\u0148 \/ <strong>h\u00e9tk\u00f6zben<\/strong> \/ Monday &#8211; Friday<br \/>\n2 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>4 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>6 Eur<\/em><\/strong><br \/>\n4 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>6 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>10 Eur<\/em><\/strong><br \/>\n6 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>8 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>15 Eur<\/em><\/strong><br \/>\n8 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>10 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>20 Eur<\/em><\/strong><\/p>\n<p>V\u00edkend \/ <strong>h\u00e9tv\u00e9ge<\/strong> \/ Weekend<br \/>\n2 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>6 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>11 Eur<\/em><\/strong><br \/>\n4 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>8 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>15 Eur<\/em><\/strong><br \/>\n6 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>10 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>20 Eur<\/em><\/strong><br \/>\n8 hod. \/ <strong>\u00f3ra<\/strong> \/ hour: kajak\/kayak &#8211; <strong><em>12 Eur<\/em><\/strong>, kanoe\/canoe &#8211; <strong><em>25 Eur<\/em><\/strong><\/p>\n<p>V pr\u00edpade pren\u00e1jmu na 3 a viac dn\u00ed je cena kajaku na de\u0148 7 Eur, a kanoe na de\u0148: 10 Eur.<\/p>\n<p>3 \u00e9s t\u00f6bb nap eset\u00e9n egy kajak b\u00e9rleti d\u00edja 7 Eur\u00f3\/nap, kenu 10 Eur\u00f3\/nap.<\/p>\n<p>Rent of kayaks for 3 or more days 7 Eur\/day, canoe 10 Eur\/day.<\/p>\n<p>V pr\u00edpade skupinovej rezerv\u00e1cie: nad 10 os\u00f4b, poskytujeme 10%-n\u00fa z\u013eavu.<\/p>\n<p>Csoportos b\u00e9rl\u00e9s (10 f\u0151 felett) eset\u00e9n 10% \u00e1rengedm\u00e9nyt adunk.<\/p>\n<p>Group reservation (10 or more people) 10% discount.[\/vc_column_text][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_separator color=&#8220;custom&#8220; accent_color=&#8220;rgba(0,0,0,0.01)&#8220;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8220;.vc_custom_1622028858317{margin-top: 70px !important;}&#8220;][vc_column][vc_column_text] HISTORICK\u00c9 Z\u00c1\u017dITKY [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1622697089556{border-bottom-width: 50px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text] CESTUJ V \u010cASE [\/vc_column_text][vc_single_image image=&#8220;2480&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#vrjatekok&#8220; el_id=&#8220;shadow1&#8243;][vc_single_image image=&#8220;2477&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#korpanorama&#8220; el_id=&#8220;shadow1&#8243;][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_single_image<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Z\u00c1\u017dITKY - BORSI R\u00c1K\u00d3CZI KAST\u00c9LY<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Z\u00c1\u017dITKY - BORSI R\u00c1K\u00d3CZI KAST\u00c9LY\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8220;.vc_custom_1622028858317{margin-top: 70px !important;}&#8220;][vc_column][vc_column_text] HISTORICK\u00c9 Z\u00c1\u017dITKY [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1622697089556{border-bottom-width: 50px !important;}&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text] CESTUJ V \u010cASE [\/vc_column_text][vc_single_image image=&#8220;2480&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#vrjatekok&#8220; el_id=&#8220;shadow1&#8243;][vc_single_image image=&#8220;2477&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;#korpanorama&#8220; el_id=&#8220;shadow1&#8243;][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_single_image [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/\" \/>\n<meta property=\"og:site_name\" content=\"BORSI R\u00c1K\u00d3CZI KAST\u00c9LY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T17:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Predpokladan\u00fd \u010das \u010d\u00edtania\">\n\t<meta name=\"twitter:data1\" content=\"6 min\u00fat\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.borsikastely.eu\/#website\",\"url\":\"https:\/\/www.borsikastely.eu\/\",\"name\":\"BORSI R\\u00c1K\\u00d3CZI KAST\\u00c9LY\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.borsikastely.eu\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/#webpage\",\"url\":\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/\",\"name\":\"Z\\u00c1\\u017dITKY - BORSI R\\u00c1K\\u00d3CZI KAST\\u00c9LY\",\"isPartOf\":{\"@id\":\"https:\/\/www.borsikastely.eu\/#website\"},\"datePublished\":\"2021-05-26T11:34:20+00:00\",\"dateModified\":\"2026-04-23T17:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.borsikastely.eu\/sk\/\",\"url\":\"https:\/\/www.borsikastely.eu\/sk\/\",\"name\":\"Kezd\\u0151lap\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/\",\"url\":\"https:\/\/www.borsikastely.eu\/sk\/zazitky\/\",\"name\":\"Z\\u00c1\\u017dITKY\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/pages\/1205"}],"collection":[{"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":50,"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/pages\/1205\/revisions"}],"predecessor-version":[{"id":5540,"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/pages\/1205\/revisions\/5540"}],"wp:attachment":[{"href":"https:\/\/www.borsikastely.eu\/sk\/wp-json\/wp\/v2\/media?parent=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}